{"id":60171,"date":"2022-12-08T18:17:14","date_gmt":"2022-12-09T00:17:14","guid":{"rendered":"https:\/\/www.lincolngoldfinch.com\/?p=60171"},"modified":"2026-03-09T22:09:40","modified_gmt":"2026-03-10T03:09:40","slug":"que-deberes-tiene-un-especialista-de-atencion-al-cliente","status":"publish","type":"post","link":"https:\/\/www.lincolngoldfinch.com\/es\/vlog\/que-deberes-tiene-un-especialista-de-atencion-al-cliente\/","title":{"rendered":"Tareas que realiza un especialista en atenci\u00f3n al cliente"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-text-transform:none;\"><p style=\"text-align: center;\"><strong>\u00bbEl show sin fronteras\u00bb<\/strong><\/p>\n<\/div><div class=\"fusion-video fusion-youtube\" style=\"--awb-max-width:733px;--awb-max-height:412px;--awb-align-self:center;--awb-width:100%;\"><div class=\"video-shortcode\"><lite-youtube videoid=\"Hr2tMwX792E\" class=\"landscape\" params=\"wmode=transparent&autoplay=1&amp;enablejsapi=1\" title=\"\u00bfQu\u00e9 Labores Realiza Un Especialista De Atenci\u00f3n Al Cliente?\" data-button-label=\"Play Video\" width=\"733\" height=\"412\" data-thumbnail-size=\"auto\" data-no-cookie=\"on\"><\/lite-youtube><\/div><\/div><div class=\"fusion-text fusion-text-2\" style=\"--awb-text-transform:none;\"><p><span style=\"font-weight: 400;\">Para responder qu\u00e9 tareas realiza un especialista en atenci\u00f3n al cliente, hay que fijarse en sus actividades b\u00e1sicas del d\u00eda a d\u00eda. Este puesto en una frma de abogados ha despertado la curiosidad de muchos. La mayor\u00eda de la gente ni siquiera sabe que dicho puesto existe.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A la hora de mantener una empresa, es esencial recordar c\u00f3mo se sienten los clientes. Es m\u00e1s importante que los ingresos que genera al mes. As\u00ed, la gente te dejar\u00e1 buenas cr\u00edticas e incluso te recomendar\u00e1 a otras personas. Pero la pregunta es: \u00bfc\u00f3mo conseguir que sigan confiando en su servicio? \u00bfC\u00f3mo conseguir que vuelvan? Ah\u00ed es donde entra en juego el <a href=\"https:\/\/es.wikipedia.org\/wiki\/Servicio_de_atenci%C3%B3n_al_cliente\" target=\"_blank\" rel=\"noopener\">servicio de atenci\u00f3n al cliente<\/a>.<\/span><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-60177\" src=\"https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2023\/11\/recibir-asistencia-integral-de-un-especialista-en-servicio-al-cliente-en-una-practica-de-la-ley-de-inmigracion-a-lo-largo-de-su-caso-de-inmigracion.webp\" alt=\"Recibir Asistencia Integral De Un Especialista En Servicio Al Cliente En Una Pr\u00e1ctica De La Ley De Inmigraci\u00f3n A Lo Largo De Su Caso De Inmigraci\u00f3n\" width=\"100%\" height=\"800\" srcset=\"https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2023\/11\/recibir-asistencia-integral-de-un-especialista-en-servicio-al-cliente-en-una-practica-de-la-ley-de-inmigracion-a-lo-largo-de-su-caso-de-inmigracion-200x133.webp 200w, https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2023\/11\/recibir-asistencia-integral-de-un-especialista-en-servicio-al-cliente-en-una-practica-de-la-ley-de-inmigracion-a-lo-largo-de-su-caso-de-inmigracion-400x267.webp 400w, https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2023\/11\/recibir-asistencia-integral-de-un-especialista-en-servicio-al-cliente-en-una-practica-de-la-ley-de-inmigracion-a-lo-largo-de-su-caso-de-inmigracion-600x400.webp 600w, https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2023\/11\/recibir-asistencia-integral-de-un-especialista-en-servicio-al-cliente-en-una-practica-de-la-ley-de-inmigracion-a-lo-largo-de-su-caso-de-inmigracion-768x512.webp 768w, https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2023\/11\/recibir-asistencia-integral-de-un-especialista-en-servicio-al-cliente-en-una-practica-de-la-ley-de-inmigracion-a-lo-largo-de-su-caso-de-inmigracion-800x533.webp 800w, https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2023\/11\/recibir-asistencia-integral-de-un-especialista-en-servicio-al-cliente-en-una-practica-de-la-ley-de-inmigracion-a-lo-largo-de-su-caso-de-inmigracion-1000x667.webp 1000w, https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2023\/11\/recibir-asistencia-integral-de-un-especialista-en-servicio-al-cliente-en-una-practica-de-la-ley-de-inmigracion-a-lo-largo-de-su-caso-de-inmigracion.webp 1200w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<h2>\u00bfQu\u00e9 tareas realiza un especialista en atenci\u00f3n al cliente?<\/h2>\n<p><span style=\"font-weight: 400;\">Puede evitar que los clientes vuelvan a acudir a usted generando confianza. Esa es la primera y principal tarea de un especialista en atenci\u00f3n al cliente. Lo mejor ser\u00eda generar confianza creando esa conexi\u00f3n entre el equipo legal y el cliente. No se trata solo del abogado y el cliente, sino de toda la firma.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Estos especialistas tambi\u00e9n tienen un equipo, un equipo de atenci\u00f3n al cliente. Incluye supervisores, pilares y apoyo que siempre est\u00e1n al tel\u00e9fono para hablar con los clientes. Este equipo es responsable de lo que ocurre detr\u00e1s de las puertas de una frma de abogados. Trabajan abriendo un caso y ocup\u00e1ndose de \u00e9l hasta que llega a un abogado.<\/span><\/p>\n<h2>Actividades cotidianas de un especialista en atenci\u00f3n al cliente<\/h2>\n<p><span style=\"font-weight: 400;\">Lo m\u00e1s importante que hace a diario un agente de atenci\u00f3n al cliente es ocuparse de los clientes. Deben escucharle porque son su primera persona de contacto durante todo el proceso. Aparte de eso, te ofrecen tranquilidad, para que sepas que te est\u00e1n cuidando. O que, aunque no sean abogados, sean la primera persona que le d\u00e9 informaci\u00f3n sobre su caso. Est\u00e1n ah\u00ed para escuchar sus preocupaciones y transmitir esos mensajes al abogado y a los asistentes legales.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es esencial que los clientes conf\u00eden en sus agentes porque existen para cuidar de ellos. Por lo general, la mayor\u00eda de los especialistas en actividades cotidianas incluyen escuchar al cliente por tel\u00e9fono. Tambi\u00e9n incluye revisar documentos y responder correos electr\u00f3nicos y mensajes de texto. Pero lo m\u00e1s importante es que crees y mantengas esa comunicaci\u00f3n directa con el cliente potencial.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tambi\u00e9n es importante se\u00f1alar que los representantes de los clientes contactan directamente con sus abogados internos. Esto se debe a que la mayor\u00eda de los clientes que se ponen en contacto con nosotros tienen esa duda simplemente porque no est\u00e1n familiarizados con ese puesto en una frma de abogados.<\/span><\/p>\n<h3>Los servicios de atenci\u00f3n al cliente reciben formaci\u00f3n<\/h3>\n<p><span style=\"font-weight: 400;\">La mayor\u00eda de las personas que llaman dudan de que los especialistas de atenci\u00f3n al cliente les est\u00e9n asesorando honestamente. Es comprensible porque exigir un proceso de inmigraci\u00f3n es complicado y estresante. Pero los clientes deben saber que las personas que atienden sus llamadas tambi\u00e9n reciben formaci\u00f3n sobre inmigraci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por eso saben lo complicados que son estos casos y c\u00f3mo manejarlos. Lleva tiempo, dinero y un largo proceso. Los agentes de atenci\u00f3n al cliente saben todo esto, y por eso atenderles significa tambi\u00e9n darles apoyo emocional.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los aspirantes a inmigrantes buscan apoyo emocional al mismo tiempo que contratan a un abogado de inmigraci\u00f3n. Pero antes de dirigirse directamente a un abogado, deben hablar con el servicio de atenci\u00f3n al cliente de esa empresa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Una vez que su informaci\u00f3n est\u00e9 lista, su caso se remitir\u00e1 a un representante legal. La raz\u00f3n principal es que los abogados siempre est\u00e1n ocupados tramitando diversos casos y asistiendo a los tribunales. As\u00ed, como primer punto de contacto, est\u00e1n los representantes de los clientes.<\/span><\/p>\n<h2>Dar apoyo emocional al cliente<\/h2>\n<p><span style=\"font-weight: 400;\">Imaginemos que hay un proceso de asilo o inmigraci\u00f3n que el cliente lleva meses o a\u00f1os esperando. Siguen esperando y no conocen el proceso, as\u00ed que te llaman a ti. Ah\u00ed es donde puedes entrar t\u00fa para apoyar emocionalmente al cliente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s de atender llamadas, correos electr\u00f3nicos y mensajes de texto, los especialistas tambi\u00e9n apoyan emocionalmente a los clientes. Es m\u00e1s de empat\u00eda. Como servicio de atenci\u00f3n al cliente, hay que ser muy emp\u00e1tico y ponerse siempre en el lugar del cliente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Asimismo, la calidad prima sobre la cantidad. Por ejemplo, puede tener tres llamadas al mismo tiempo. Pero siempre hay que prestar especial atenci\u00f3n a cada uno porque son personas. Comprende que cada persona tiene un caso diferente y que su situaci\u00f3n es igual de importante.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Todos los seres humanos pasamos por situaciones dif\u00edciles, y debes dedicar emoci\u00f3n y sentimientos a ese cliente. As\u00ed, sienten que son igual de importantes. Del mismo modo, trabajar en atenci\u00f3n al cliente no consiste en vender un caso. Se trata de cambiar una vida.<\/span><\/p>\n<h2>Responder a las preguntas lo antes posible<\/h2>\n<p><span style=\"font-weight: 400;\">Los abogados siempre est\u00e1n ocupados tramitando casos, acudiendo a los tribunales y revisando situaciones en una frma. Por eso, el equipo de atenci\u00f3n al cliente ofrece orientaci\u00f3n o revisiones directas a las personas que quieran comentar sus casos. Los especialistas en atenci\u00f3n al cliente son expertos en servicio al cliente. Responden a las preguntas de los clientes y les ayudan a desarrollar su caso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, como agente, debe crear un v\u00ednculo entre el cliente y el abogado. Adem\u00e1s, tambi\u00e9n apoyas al equipo legal en sus tareas. Es el primer contacto despu\u00e9s de la consulta y alguien a quien puede llamar inmediatamente si necesita algo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si un cliente env\u00eda un correo electr\u00f3nico, el agente responde a sus preguntas lo antes posible. Las firmas de abogados tienen pol\u00edticas internas en las que el servicio de atenci\u00f3n al cliente debe responder a los clientes con prontitud.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De este modo, saben que el equipo ha recibido el mensaje. Sin embargo, no siempre es en un par de minutos, ya que a veces puede tardar hasta horas en dar una respuesta.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pero lo mejor del equipo de atenci\u00f3n al cliente es el apoyo desde el principio hasta el final de una solicitud o caso.<\/span><\/p>\n<h2>Atenci\u00f3n al cliente de una firma de abogados<\/h2>\n<p><span style=\"font-weight: 400;\">Como la mayor\u00eda de la gente no sabe que las frmas de abogados tienen representantes de atenci\u00f3n al cliente, he aqu\u00ed lo que hacen. La mayor\u00eda de las firmas de abogados ofrecen un servicio de atenci\u00f3n al cliente para obtener informaci\u00f3n b\u00e1sica del cliente e informarle de sus opciones. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tambi\u00e9n dan informaci\u00f3n sobre el desarrollo de un caso. Todo el equipo de atenci\u00f3n al cliente tambi\u00e9n prev\u00e9 y anticipa las necesidades del cliente y se pone en contacto con el <a href=\"https:\/\/www.lincolngoldfinch.com\/es\/\">abogado m\u00e1s accesible.<\/a> Adem\u00e1s, hablar con un agente no va a ser un juego de tel\u00e9fono. Ofrecen el apoyo emocional, la tranquilidad y la confianza que un cliente necesita, sobre todo cuando se siente perdido.<\/span><\/p>\n<h2>Reuniones con el equipo legal<\/h2>\n<p><span style=\"font-weight: 400;\">Las reuniones con el equipo legal son esenciales. Pero lo m\u00e1s importante es que todos deben asistir a la reuni\u00f3n. A veces, los especialistas no pueden acudir r\u00e1pidamente debido a un caso. O los abogados s\u00f3lo est\u00e1n disponibles a trav\u00e9s del chat o el correo electr\u00f3nico. Pero el objetivo principal es la comunicaci\u00f3n directa y poder hablar de cada caso concreto.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lo m\u00e1s importante de las reuniones es revisar lo m\u00e1s urgente y nuevo. Tambi\u00e9n se trata de encontrar de qu\u00e9 podemos hablar y c\u00f3mo resolver una situaci\u00f3n. Hay varias reuniones cada semana, y todo es importante. As\u00ed es como los agentes de atenci\u00f3n al cliente se comunican con sus asistentes legales y abogados para saber c\u00f3mo gestionar los casos.<\/span><\/p>\n<h2>\u00bfQu\u00e9 es lo m\u00e1s importante de ser especialista en atenci\u00f3n al cliente?<\/h2>\n<p><img decoding=\"async\" class=\"size-full wp-image-60179 alignright\" src=\"https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2023\/11\/beneficiese-del-apoyo-ofrecido-por-un-especialista-en-servicio-al-cliente-de-una-firma-de-inmigracion-durante-su-caso-de-inmigracion.jpg\" alt=\"Benef\u00edciese Del Apoyo Ofrecido Por Un Especialista En Servicio Al Cliente De Una Firma De Inmigraci\u00f3n Durante Su Caso De Inmigraci\u00f3n\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2023\/11\/beneficiese-del-apoyo-ofrecido-por-un-especialista-en-servicio-al-cliente-de-una-firma-de-inmigracion-durante-su-caso-de-inmigracion-200x133.jpg 200w, https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2023\/11\/beneficiese-del-apoyo-ofrecido-por-un-especialista-en-servicio-al-cliente-de-una-firma-de-inmigracion-durante-su-caso-de-inmigracion.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Una de las habilidades m\u00e1s importantes de un especialista en atenci\u00f3n al cliente es prestar atenci\u00f3n a los detalles. Hay que escuchar de verdad a los clientes y lo que dicen. Cada detalle es importante porque puede influir en la resoluci\u00f3n de su caso. Se trata de prestar atenci\u00f3n, no olvidar los mensajes y comunicarse claramente con los abogados y los asistentes jur\u00eddicos.<\/span><\/p>\n<h2>Tratar con un profesional del derecho los asuntos de inmigraci\u00f3n<\/h2>\n<p><span style=\"font-weight: 400;\">En lo que respecta a cuestiones o problemas de inmigraci\u00f3n, no vaya con cualquiera que le ofrezca un documento. Aseg\u00farese de tratar con un profesional del Derecho que se preocupe por usted como cliente y le genere confianza.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si primero ha hablado con usted un especialista de atenci\u00f3n al cliente en lugar de un abogado, conf\u00ede en \u00e9l. Habla con ellos y cu\u00e9ntales tu caso con sinceridad. Como ya se ha dicho, son su primer punto de contacto. Tenga la seguridad de que sus mensajes y preocupaciones ser\u00e1n transmitidos a los legistas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cada cliente es valioso para el servicio de atenci\u00f3n al cliente, y lo cuidan como a una planta. Facilitan informaci\u00f3n a todo el mundo y despejan cualquier duda o temor sobre su proceso de inmigraci\u00f3n. Ayudan a los clientes a crecer y prosperar, celebrando con ellos cuando han completado casos con \u00e9xito.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Son especialistas en atenci\u00f3n al cliente y saben c\u00f3mo tratar las preocupaciones de los clientes. Puede que no sean abogados, pero existen para confiar en sus mensajes a sus asistentes legales y abogados lo antes posible.<\/span><\/p>\n<p>Si tiene m\u00e1s preguntas sobre nuestros especialistas de atenci\u00f3n al cliente, casos de inmigraci\u00f3n o su caso concreto, puede ponerse en contacto con nosotros en el <a href=\"tel:+1-855-502-0555\"> tel\u00e9fono (855) 502-0555<\/a>. Despu\u00e9s de una breve evaluaci\u00f3n de 10 minutos de su caso por tel\u00e9fono, le haremos saber qu\u00e9 opciones tiene. Tambi\u00e9n puedes seguirnos en nuestras redes sociales para no perderte nuestras emisiones semanales en <a href=\"https:\/\/www.facebook.com\/lincolngoldfinch\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>, <a href=\"https:\/\/www.youtube.com\/c\/Lincolngoldfinchlawatx\/\" target=\"_blank\" rel=\"noopener noreferrer\">YouTube<\/a> y <a href=\"https:\/\/www.twitch.tv\/lincolngoldfinch\" target=\"_blank\" rel=\"noopener noreferrer\">Twitch<\/a>.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><\/div><\/div><\/div><\/div>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"vlog,inmigracion-vlogs-es\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1670523434\"\r\n\t            data-title=\"Tareas que realiza un especialista en atenci\u00f3n al cliente\" \r\n\t            data-home=\"https:\/\/www.lincolngoldfinch.com\/es\/\"><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":60159,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","_analytify_skip_tracking":false,"rank_math_title":"\u00bfQu\u00e9 deberes tiene un especialista en atencion al cliente?","rank_math_description":"Lincoln-Goldfinch habla del papel y responsabilidades de un especialista en atenci\u00f3n al cliente dentro del equipo jur\u00eddico.","rank_math_focus_keyword":"atenci\u00f3n al cliente","rank_math_canonical_url":"","footnotes":""},"categories":[1934,1938],"class_list":["post-60171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vlog","category-inmigracion-vlogs-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/posts\/60171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/comments?post=60171"}],"version-history":[{"count":0,"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/posts\/60171\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/media\/60159"}],"wp:attachment":[{"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/media?parent=60171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/categories?post=60171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}