{"id":34671,"date":"2022-07-13T16:44:13","date_gmt":"2022-07-13T21:44:13","guid":{"rendered":"https:\/\/www.lincolngoldfinch.com\/?p=34671"},"modified":"2026-05-07T17:37:22","modified_gmt":"2026-05-07T22:37:22","slug":"que-es-el-prima-facie-en-un-caso-de-vawa","status":"publish","type":"post","link":"https:\/\/www.lincolngoldfinch.com\/es\/vlog\/que-es-el-prima-facie-en-un-caso-de-vawa\/","title":{"rendered":"\u00bfQu\u00e9 es el Prima Facie en un caso de VAWA?"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p style=\"text-align: center;\">\u00bbEl show sin fronteras\u00bb<\/p>\n<\/div><div class=\"fusion-text fusion-text-2\" style=\"--awb-text-transform:none;\"><h2>\u00bfQu\u00e9 es la determinaci\u00f3n Prima Facie?<\/h2>\n<p>La Primera Vista, que en ingl\u00e9s es Prima Facie Determination, lo que quiere decir es que inmigraci\u00f3n ha recibido una solicitud para VAWA.<\/p>\n<p>Usamos la forma I-360 que es una forma que usamos para ver los tipos de casos, pero eso es lo que usamos para VAWA.<\/p>\n<p>En un caso de VAWA hay requisitos para calificar o para pasar el paso de la oficina de correos que revisan todos los paquetes.<\/p>\n<p>Para un matrimonio de buena fe se tiene que probar que el aplicante ha sufrido de maltrato o un tipo de abuso en la relaci\u00f3n, esa persona tambi\u00e9n tiene que probar que tiene buen car\u00e1cter moral.<\/p>\n<p>A veces tenemos que entregar un documento del Estado de Texas diciendo que la persona nunca ha sido arrestada, y despu\u00e9s de mandar ese forma con la evidencia requerida, alguien en la agencia de inmigraci\u00f3n va a revisar las cajas y decir que esa persona ha enviado la evidencia m\u00ednima requerida para un caso de VAWA.<\/p>\n<p>Esto no quiere decir que el caso ya ha sido revisado, en lo que han quedado es en que no hay una decisi\u00f3n en el caso, pero la Prima Facie Determination solo quiere decir que el aplicante ha enviado la evidencia requerida en un caso de VAWA.<\/p>\n<p><img decoding=\"async\" class=\"alignleft wp-image-60057 size-full\" src=\"https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2022\/07\/que-es-el-programa-vawa.jpg\" alt=\"If You Are In Situation Of Violence Or Abuse, Don't Hesitate To Contact Lincoln-Goldfinch Law\" width=\"799\" height=\"450\" srcset=\"https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2022\/07\/que-es-el-programa-vawa-200x113.jpg 200w, https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2022\/07\/que-es-el-programa-vawa-400x225.jpg 400w, https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2022\/07\/que-es-el-programa-vawa-600x338.jpg 600w, https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2022\/07\/que-es-el-programa-vawa-768x433.jpg 768w, https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2022\/07\/que-es-el-programa-vawa.jpg 799w\" sizes=\"(max-width: 799px) 100vw, 799px\" \/><\/p>\n<p>Los aplicantes viviendo en Texas no tienen muchos beneficios, una carta de Prima Facie son buenas noticias porque quiere decir ha pasado el primer paso de pedir el caso, pero aparte de eso, no viene con muchos beneficios.<\/p>\n<p>Cuando alguien recibe un Prima Facie Determination puede celebrar, porque esa evidencia que ha enviado en su solicitud a inmigraci\u00f3n, la ha aceptado en su caso.<\/p>\n<h2>\u00bfQu\u00e9 es el programa VAWA? Y tiempos de espera<\/h2>\n<p>VAWA es la Visa para personas que han sido v\u00edctimas de crueldad en una relaci\u00f3n y est\u00e1n pidi\u00e9ndole a inmigraci\u00f3n protecci\u00f3n y ajuste de su estatus migratorio sin la ayuda de su abusador.<\/p>\n<p>Normalmente el 80% o 90% de los casos, estamos solicitando VAWA y la residencia permanente en un paso se llama One-Step.<\/p>\n<p>En ese proceso entregamos la forma I-360 y la forma I-485 que es el ajuste de estatus de residente permanente, siempre y cuando alguien est\u00e9 haciendo un ajuste de estatus.<\/p>\n<p>Viene con una elegibilidad para pedir un permiso de trabajo que normalmente llega en unos seis a nueve meses despu\u00e9s de solicitar la residencia permanente.<\/p>\n<p>Si estamos haciendo un caso de VAWA One-Step que es la mayor\u00eda de casos, el proceso ser\u00eda que entregamos el paquete con todas las formas, toda la evidencia, luego llegan los recibos que tienen el n\u00famero de caso, luego tres meses despu\u00e9s llega el Prima Facie Determination que solo dice que ha entregado la evidencia requerida pero el caso todav\u00eda sigue pendiente.<\/p>\n<p>De seis a nueve meses despu\u00e9s de solicitar VAWA es cuando llega el permiso de trabajo.<\/p>\n<p>En el Estado de Texas con ese permiso de trabajo usted puede sacar la licencia y el seguro social.<\/p>\n<p>Existe un porcentaje de casos en donde no solicitamos el ajuste de estatus a residente permanente al mismo tiempo que VAWA, y normalmente lo hacemos cuando alguien cuenta con un castigo, tiene delitos, varias entradas, ha dicho que era ciudadano en los EE.UU. o hay complicaciones en su historia.<\/p>\n<p>Hay ciertas personas que no deben solicitar residencia permanente porque es riesgoso, para ellos solicitamos primero VAWA, obtenemos la aprobaci\u00f3n y luego, en ocasiones podemos solicitar la residencia permanente.<\/p>\n<p>Esas personas no califican para el permiso de trabajo cuando el caso est\u00e1 pendiente, ellos van a tener que esperar hasta que su caso de VAWA est\u00e9 aprobado con inmigraci\u00f3n, y eso puede llegar a demorar entre un a\u00f1o y dos a\u00f1os.<\/p>\n<p>Generalmente ser\u00eda un a\u00f1o y medio de espera solo para el permiso de trabajo.<\/p>\n<h2>\u00bfSi no me lleg\u00f3 la prima facie significa que me negaron VAWA?<\/h2>\n<p><img decoding=\"async\" class=\"size-full wp-image-34744 alignleft\" src=\"https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2022\/07\/el-abuso-domestico-abarca-a-familiares-agresivos-que-irrespetan-a-sus-padres.jpg\" alt=\"El Abuso Dom\u00e9stico Abarca A Familiares Agresivos Que Irrespetan A Sus Padres\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2022\/07\/el-abuso-domestico-abarca-a-familiares-agresivos-que-irrespetan-a-sus-padres-200x133.jpg 200w, https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2022\/07\/el-abuso-domestico-abarca-a-familiares-agresivos-que-irrespetan-a-sus-padres.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>La determinaci\u00f3n de Prima Facie es la parte del proceso migratorio que dice que inmigraci\u00f3n ha revisado el paquete y ha dicho que los m\u00ednimos requisitos para ese tipo de caso han sido hechos.<\/p>\n<p>En Texas no hay muchos beneficios p\u00fablicos para esas personas, no hay siquiera elegibilidad para una licencia.<\/p>\n<p>En otros Estados hay manera de obtener beneficios p\u00fablicos, de sacar una licencia, por ejemplo, esa noticia de Prima Facie que el inmigrante obtiene es m\u00e1s s\u00f3lida, tiene m\u00e1s beneficios incorporados, pero aqu\u00ed en Texas hay son pocos los beneficios p\u00fablicos.<\/p>\n<p>En Texas, a\u00fan no es posible sacar la licencia hasta que obtenga el permiso de trabajo que mayormente para los que est\u00e1n arreglando (aproximadamente un 90% de los aplicantes) van a recibir el permiso en seis meses, y el resto puede esperar un a\u00f1o y medio para obtener su permiso de trabajo.<\/p>\n<h2>\u00bfSi me lleg\u00f3 la prima facie todav\u00eda pueden negar mi visa?<\/h2>\n<p>S\u00ed, s\u00ed es algo que es posible porque esta noticia solo nos dice que la que la evidencia ha sido entregada, pero no han revisado los detalles del caso todav\u00eda.<\/p>\n<p>Es posible recibir una decisi\u00f3n negativa, pero normalmente en inmigraci\u00f3n si alguien recibe la determinaci\u00f3n de Prima Facie y el oficial est\u00e1 revisando el caso y decide que algo falta o que hay una carta de un testigo que no es suficiente.<\/p>\n<p>Ellos no van a negar su caso, lo que van a hacer es mandar una respuesta solicitando m\u00e1s evidencia.<\/p>\n<p>En ingl\u00e9s es una <a href=\"https:\/\/www.boundless.com\/immigration-resources\/what-is-a-request-for-evidence-rfe-and-what-should-i-do-about-it\/\" target=\"_blank\" rel=\"noopener\">Request For Evidence<\/a> o RFE, y eso quiere decir que inmigraci\u00f3n est\u00e1 pidiendo m\u00e1s documentos, m\u00e1s evidencia, m\u00e1s informaci\u00f3n, y hay un periodo de tiempo para responder esa noticia, normalmente es\u00a0 de 30 d\u00edas, pero a veces pueden ser hasta 90 d\u00edas para responder.<\/p>\n<p>Es muy importante responder a esas noticias o respuestas en el tiempo que les dan porque si no, inmigraci\u00f3n negar\u00e1 el caso.<\/p>\n<h2>\u00bfSi recib\u00ed la notificaci\u00f3n prima facie puedo salir del pa\u00eds?<\/h2>\n<p>Recibir la Prima Facie no quiere decir que usted puede viajar o que puede sacar una licencia o un permiso de trabajo, de todas formas s\u00ed son buenas noticias porque eso quiere decir que va en camino este paso, pero no quiere decir algo m\u00e1s para un aplicante, nada va a cambiar hasta que obtenga el permiso de trabajo.<\/p>\n<p>Si alguien quiere viajar fuera de los EE.UU. va a necesitar un Advance Parole,\u00a0 para la mayor\u00eda de aplicantes no es recomendable viajar fuera de los EE.UU. hasta que haya obtenido su residencia permanente.<\/p>\n<p>Se entiende que hay emergencias que se puedan presentar en el camino, y cada persona que est\u00e1 en esta situaci\u00f3n de su caso pendiente tiene que hablar con su abogado antes de hacer cualquier viaje.<\/p>\n<p>Si usted es cliente de Lincoln-Goldfinch Law &#8211; Abogados de Inmigraci\u00f3n,\u00a0 sabe que un familiar importante est\u00e1 enfermo y va a tener que o va a querer poder visitar a esa persona dentro de un mes, eso es tiempo, ahora es tiempo para hablar con nosotros para averiguar si hay una manera de obtener un permiso para salir.<\/p>\n<h2>\u00bfPrima facie tiene la misma protecci\u00f3n que VAWA?<\/h2>\n<p>Hay una parte de la ley, la 1367, que dice que cuando alguien ha solicitado VAWA ha entregado por correo la forma I-360 a inmigraci\u00f3n e inmigraci\u00f3n ha recibido su paquete.<\/p>\n<p>La agencia de inmigraci\u00f3n tiene prohibido hablar con el agresor en esa situaci\u00f3n, esto quiere decir que ellos no pueden compartir informaci\u00f3n pero tampoco pueden aceptar informaci\u00f3n del agresor, porque sabemos que es muy com\u00fan en una relaci\u00f3n violenta, que el agresor use amenazas de deportaci\u00f3n llamando a inmigraci\u00f3n para controlar a su v\u00edctima.<\/p>\n<p>Por eso tenemos esta protecci\u00f3n en la ley diciendo que cuando alguien ha solicitado VAWA ellos son protegidos y el agresor no puede hablar con inmigraci\u00f3n sobre esta persona, no puede hacer reportes, amenazas o cualquier cosa que se le ocurra.<\/p>\n<p>Esta protecci\u00f3n empieza en el momento en que inmigraci\u00f3n recibe la solicitud Prima Facie, pero el aviso de Prima Facie no tiene nada que ver con esa protecci\u00f3n.<\/p>\n<h2>\u00bfSi no recib\u00ed mi prima facie a\u00fan, me negar\u00e1n VAWA?<\/h2>\n<p><img decoding=\"async\" class=\"size-full wp-image-34746 alignright\" src=\"https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2022\/07\/consulte-sin-temor-sus-opciones-legales-migratorias-para-obtener-un-ajuste-de-estatus-en-estados-unidos.jpg\" alt=\"Consulte Sin Temor Sus Opciones Legales Migratorias Para Obtener Un Ajuste De Estatus En Estados Unidos\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2022\/07\/consulte-sin-temor-sus-opciones-legales-migratorias-para-obtener-un-ajuste-de-estatus-en-estados-unidos-200x133.jpg 200w, https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2022\/07\/consulte-sin-temor-sus-opciones-legales-migratorias-para-obtener-un-ajuste-de-estatus-en-estados-unidos.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Es muy com\u00fan que un aplicante para VAWA no tenga evidencia oficial, como un reporte a la polic\u00eda, porque no es requerido, recuerde que no es necesario haber hecho un reporte con la polic\u00eda para calificar para pedir VAWA.<\/p>\n<p>Cuando alguien ha estado en una en una relaci\u00f3n violenta es algo secreto, ellos no comparten esa informaci\u00f3n con el p\u00fablico a veces toman fotos de moretones o tienen evidencia escondida y eso es de ayuda en un caso.<\/p>\n<p>Estamos muy acostumbrados a trabajar con clientes que no tienen evidencia y vienen a nuestra oficina muy preocupados por esa pregunta de la evidencia, pero somos creativos en encontrar evidencia en cada caso.<\/p>\n<p>Por ejemplo, podemos empezar servicios con un psic\u00f3logo y que esa persona pueda escribir una carta de testimonio despu\u00e9s de tener varias citas con la v\u00edctima, o podemos entregar cartas de su mejor amigo que sab\u00eda lo que estaba pasando.<\/p>\n<p>Si alguien entrega un caso que no tiene suficiente evidencia, van a recibir una noticia RFE (Request For Evidence) solicitando m\u00e1s evidencia.<\/p>\n<h2>\u00bfDebo solicitar VAWA si no tengo evidencia?<\/h2>\n<p>Desde <a href=\"https:\/\/www.lincolngoldfinch.com\/\" target=\"_blank\" rel=\"noopener\">Lincoln-Goldfinch Law &#8211; Abogados de Inmigraci\u00f3n<\/a>, nuestro consejo para todos los inmigrantes que est\u00e1n dudando de comenzar un proceso de inmigraci\u00f3n por la falta de evidencia, es que no duden, porque en esta firma somos profesionales creativos, podemos encontrar evidencia y armar con ella la mejor estrategia para su caso.<\/p>\n<p>Parte de nuestro trabajo es encontrar evidencia para probar un caso, llenar las formas, enviar la evidencia y las cuotas, esos detalles son parte de nuestro trabajo m\u00e1s importante, la estrategia y la evidencia, porque estamos de su lado en su caso.<\/p>\n<p>Si usted se encuentra con dudas o siente que no es posible ajustar su estatus migratorio, sea cual sea la situaci\u00f3n por la que usted est\u00e9 pasando, no pierda la oportunidad de llamarnos y saber en ese primer contacto si seremos capaces de ayudarle y comenzar un camino migratorio que cambiar\u00e1 su vida.<\/p>\n<p>En caso de que tenga m\u00e1s preguntas sobre Prima Facie, su evidencia, o su caso espec\u00edfico, puede ponerse en contacto con nosotros en el <a href=\"tel:+1-855-502-0555\"> tel\u00e9fono (855) 502-0555<\/a>. Despu\u00e9s de una breve evaluaci\u00f3n de 10 minutos de su caso por tel\u00e9fono, le haremos saber qu\u00e9 opciones tiene. Tambi\u00e9n puedes seguirnos en nuestras redes sociales para no perderte nuestras transmisiones semanales a trav\u00e9s de <a href=\"https:\/\/www.facebook.com\/lincolngoldfinch\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>, <a href=\"https:\/\/www.youtube.com\/c\/Lincolngoldfinchlawatx\/\" target=\"_blank\" rel=\"noopener noreferrer\">YouTube<\/a> y <a href=\"https:\/\/www.twitch.tv\/lincolngoldfinch\" target=\"_blank\" rel=\"noopener noreferrer\">Twitch<\/a>.<\/p>\n<\/div><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-two\" style=\"--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h2 class=\"fusion-title-heading title-heading-center\" style=\"margin:0;\">Preguntas frecuentes prima facie determination<\/h2><\/div><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:1px;--awb-icon-size:16px;--awb-content-font-size:var(--awb-typography4-font-size);--awb-icon-alignment:left;--awb-hover-color:var(--awb-color2);--awb-border-color:var(--awb-color3);--awb-background-color:var(--awb-color1);--awb-divider-color:var(--awb-color3);--awb-divider-hover-color:var(--awb-color3);--awb-icon-color:var(--awb-color1);--awb-title-color:var(--awb-color8);--awb-content-color:var(--awb-color8);--awb-icon-box-color:var(--awb-color8);--awb-toggle-hover-accent-color:var(--awb-color5);--awb-title-font-family:var(--awb-typography1-font-family);--awb-title-font-weight:var(--awb-typography1-font-weight);--awb-title-font-style:var(--awb-typography1-font-style);--awb-title-font-size:var(--awb-typography1-font-size);--awb-title-letter-spacing:var(--awb-typography1-letter-spacing);--awb-title-line-height:var(--awb-typography1-line-height);--awb-content-font-family:var(--awb-typography4-font-family);--awb-content-font-weight:var(--awb-typography4-font-weight);--awb-content-font-style:var(--awb-typography4-font-style);\"><div class=\"panel-group fusion-toggle-icon-boxed\" id=\"accordion-34671-1\"><div class=\"fusion-panel panel-default panel-527b7969263f21e0b fusion-toggle-has-divider\" style=\"--awb-title-font-size:20px;\"><div class=\"panel-heading\"><h3 class=\"panel-title toggle\" id=\"toggle_527b7969263f21e0b\"><a aria-expanded=\"false\" aria-controls=\"527b7969263f21e0b\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-34671-1\" data-target=\"#527b7969263f21e0b\" href=\"#527b7969263f21e0b\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfQu\u00e9 Es Prima Facie Determination?<\/span><\/a><\/h3><\/div><div id=\"527b7969263f21e0b\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_527b7969263f21e0b\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>La Primera Vista, que en ingl\u00e9s es Prima Facie Determination, lo que quiere decir es que inmigraci\u00f3n ha recibido una solicitud para VAWA. Usamos la forma I-360 que es una forma que usamos para ver los tipos de casos, pero eso es lo que usamos para VAWA.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-21561edade3bec7e6 fusion-toggle-has-divider\" style=\"--awb-title-font-size:20px;\"><div class=\"panel-heading\"><h3 class=\"panel-title toggle\" id=\"toggle_21561edade3bec7e6\"><a aria-expanded=\"false\" aria-controls=\"21561edade3bec7e6\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-34671-1\" data-target=\"#21561edade3bec7e6\" href=\"#21561edade3bec7e6\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfQu\u00e9 Es El Programa VAWA?<\/span><\/a><\/h3><\/div><div id=\"21561edade3bec7e6\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_21561edade3bec7e6\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>VAWA es la Visa para personas que han sido v\u00edctimas de crueldad en una relaci\u00f3n y est\u00e1n pidi\u00e9ndole a inmigraci\u00f3n protecci\u00f3n y ajuste de su estatus migratorio sin la ayuda de su abusador. Normalmente el 80% o 90% de los casos, estamos solicitando VAWA y la residencia permanente en un paso se llama\u00a0One-Step.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-4a151490bbfc17e59 fusion-toggle-has-divider\" style=\"--awb-title-font-size:20px;\"><div class=\"panel-heading\"><h3 class=\"panel-title toggle\" id=\"toggle_4a151490bbfc17e59\"><a aria-expanded=\"false\" aria-controls=\"4a151490bbfc17e59\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-34671-1\" data-target=\"#4a151490bbfc17e59\" href=\"#4a151490bbfc17e59\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfPrima Facie Tiene La Misma Protecci\u00f3n Que VAWA?<\/span><\/a><\/h3><\/div><div id=\"4a151490bbfc17e59\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_4a151490bbfc17e59\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Esta protecci\u00f3n empieza en el momento en que inmigraci\u00f3n recibe la solicitud Prima Facie, pero la noticia de Prima Facie no tiene nada que ver con esa protecci\u00f3n.<\/p>\n<\/div><\/div><\/div><\/div><\/div>        <script type=\"application\/ld+json\">{\n\n\"@context\": \"https:\/\/schema.org\",\n\n      \"@type\": \"FAQPage\",\n\n     \"mainEntity\": [{\n\n        \"@type\": \"Question\",\n\n        \"name\": \"\u00bfQu\u00e9 Es Prima Facie Determination?\",\n\n        \"acceptedAnswer\": {\n\n          \"@type\": \"Answer\",\n\n      \"text\": \"<p>La Primera Vista, que en ingl\u00e9s es Prima Facie Determination, lo que quiere decir es que inmigraci\u00f3n ha recibido una solicitud para VAWA. Usamos la forma I-360 que es una forma que usamos para ver los tipos de casos, pero eso es lo que usamos para VAWA.<\/p>\"\n\n      }\n\n      }, {\n\n        \"@type\": \"Question\",\n\n        \"name\": \"\u00bfQu\u00e9 Es El Programa VAWA?\",\n\n        \"acceptedAnswer\": {\n\n          \"@type\": \"Answer\",\n\n          \"text\": \"<p>VAWA es la Visa para personas que han sido v\u00edctimas de crueldad en una relaci\u00f3n y est\u00e1n pidi\u00e9ndole a inmigraci\u00f3n protecci\u00f3n y ajuste de su estatus migratorio sin la ayuda de su abusador. Normalmente el 80% o 90% de los casos, estamos solicitando VAWA y la residencia permanente en un paso se llama\u00a0One-Step.<\/p>\"\n\n        }\n\n      }, {\n\n        \"@type\": \"Question\",\n\n        \"name\": \"\u00bfPrima Facie Tiene La Misma Protecci\u00f3n Que VAWA?\",\n\n        \"acceptedAnswer\": {\n\n          \"@type\": \"Answer\",\n\n          \"text\": \"<p>Esta protecci\u00f3n empieza en el momento en que inmigraci\u00f3n recibe la solicitud Prima Facie, pero la noticia de Prima Facie no tiene nada que ver con esa protecci\u00f3n.<\/p>\"\n\n        }\n\n      }]\n\n    }\n\n   <\/script><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><\/div><\/div><\/div><\/div>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"vlog,inmigracion-vlogs-es,vawa-vlogs-es\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1657730653\"\r\n\t            data-title=\"\u00bfQu\u00e9 es el Prima Facie en un caso de VAWA?\" \r\n\t            data-home=\"https:\/\/www.lincolngoldfinch.com\/es\/\"><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":34728,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","_analytify_skip_tracking":false,"rank_math_title":"Determinaci\u00f3n Prima Facie en un caso de VAWA","rank_math_description":"Consiga informaci\u00f3n relacionada sobre el Prima Facie Determination en los casos humanitarios migratorios de VAWA en EE.UU.","rank_math_focus_keyword":"vawa","rank_math_canonical_url":"https:\/\/www.lincolngoldfinch.com\/es\/vlog\/que-es-el-prima-facie-en-un-caso-de-vawa\/","footnotes":""},"categories":[1934,1938,1935],"class_list":["post-34671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vlog","category-inmigracion-vlogs-es","category-vawa-vlogs-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/posts\/34671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/comments?post=34671"}],"version-history":[{"count":1,"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/posts\/34671\/revisions"}],"predecessor-version":[{"id":107529,"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/posts\/34671\/revisions\/107529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/media\/34728"}],"wp:attachment":[{"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/media?parent=34671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/categories?post=34671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}