{"id":15828,"date":"2021-10-26T06:23:27","date_gmt":"2021-10-25T22:23:27","guid":{"rendered":"https:\/\/www.lincolngoldfinchfirm.com\/?p=15828"},"modified":"2026-03-11T17:08:13","modified_gmt":"2026-03-11T22:08:13","slug":"abogado-para-accidentes-en-el-trabajo","status":"publish","type":"post","link":"https:\/\/www.lincolngoldfinch.com\/es\/vlog\/abogado-para-accidentes-en-el-trabajo\/","title":{"rendered":"Accidentes en el trabajo"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-right:0px;--awb-padding-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-top:0px;--awb-padding-right:0px;--awb-padding-bottom:0px;--awb-padding-left:0px;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-text-transform:none;\"><p style=\"text-align: center;\"><strong>\u201dEl Show Sin Fronteras\u201d<\/strong><\/p>\n<\/div><div class='youtube_codegena' id='tdRrfNuohQQ' data-params='?&theme=dark&autoplay=1&autohide=2&modestbranding=1&fs=0&showinfo=0&rel=0' src='https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2021\/11\/the-importance-of-a-work-injury-attorney.jpg' allowfullscreen=\"allowfullscreen\" style='width:840px; height:470px;margin: 0 auto;'><\/div><script src='https:\/\/rawgit.com\/shaneapen\/Async-Youtube-Player\/master\/async_youtube_player.js'><\/script><div class=\"fusion-text fusion-text-2\" style=\"--awb-text-transform:none;--awb-margin-top:20px;\"><h2>La invitada de hoy<\/h2>\n<p>Nuestros anfitriones Karla y Fidel estuvieron acompa\u00f1ados hoy por la Abogada Cristina, quien se especializa en Accidentes para Inmigrantes. Todas las personas, todos los d\u00edas, est\u00e1n expuestas a accidentes de cualquier tipo, y hoy nos enfocamos en los accidentes laborales y la importancia de contar con un\u00a0<em>abogado de accidentes de trabajo<\/em>. Durante nuestra transmisi\u00f3n tambi\u00e9n estuvimos recibiendo todas las preguntas que nuestros espectadores tuviesen para nuestra invitada.<\/p>\n<h2>El rol de un abogado de accidentes de trabajo<\/h2>\n<p>Es com\u00fan en pa\u00edses como M\u00e9xico o pa\u00edses de habla hispana que un abogado maneje varios tipos de casos. En los Estados Unidos, y particularmente en Texas, esta situaci\u00f3n es distinta. Normalmente los abogados que toman casos de inmigraci\u00f3n, por ejemplo, se especializan en los mismos y no toman otro tipo de casos.\u00a0<strong>El despacho de la abogada Cristina se especializa en casos de Accidentes, espec\u00edficamente laborales y automovil\u00edsticos.<\/strong>\u00a0En caso de que los clientes que acuden a su despacho tengan dudas acerca de otros temas legales, son referidos a otros despachos que se especialicen en su requerimiento.<\/p>\n<h3>\u00bfEs posible obtener documentos a ra\u00edz de un accidente automovil\u00edstico?<\/h3>\n<div id=\"attachment_15832\" class=\"wp-caption alignleft\"><img decoding=\"async\" class=\"wp-image-15832 size-full\" src=\"https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2021\/10\/accidentes-laborales-abogados-evaluacion-legal-gratuita-cerca-de-mi-austin-inmigrantes.jpg\" alt=\"Abogado De Accidentes Inmigrantes Cerca De Mi\" width=\"300\" height=\"200\" aria-describedby=\"caption-attachment-15832\" \/><\/div>\n<p>Depende del caso. Si usted fue v\u00edctima de un accidente automovil\u00edstico y la otra persona se encontraba en estado de embriaguez, de manera que ese caso podr\u00eda calificar para una\u00a0<a href=\"https:\/\/www.lincolngoldfinch.com\/es\/actualizaciones-visa-u-y-permisos-de-trabajo-el-show-sin-fronteras\/\">Visa U<\/a>, en la firma de la abogada Cristina se contactar\u00e1n con nuestra firma Lincoln-Goldfinch Law &#8211; Abogados de Inmigraci\u00f3n para asesorarse adecuadamente respecto a qu\u00e9 camino tomar en materia de Inmigraci\u00f3n.\u00a0<strong>Es importante recordar que no todos los accidentes califican para obtener alg\u00fan tipo de estatus legal.<\/strong><\/p>\n<p>Karla nos cont\u00f3 acerca de la historia de un hombre que decidi\u00f3 compartirla con nosotros. Nos cont\u00f3 que se encontraba instalando un piso de madera cuando accidentalmente amput\u00f3 uno de sus dedos, y quisiera saber si es posible tomar alguna acci\u00f3n legal ya que su empresa no quiere darle ninguna compensaci\u00f3n econ\u00f3mica.<\/p>\n<p>La abogada Cristina aconseja ponerse en contacto con su despacho, todas las consultas legales relacionadas con accidentes son completamente gratis y confidenciales. Es fundamental que las personas conozcan sus derechos, y adem\u00e1s existen muchas variables que intervienen en el caso, como por ejemplo, el tipo de trabajo, a qui\u00e9n pertenecen las herramientas que estaba utilizando, si es un trabajo por horas o por proyecto, etc. Todo esto para poder clasificarlo como Trabajador o Contratista, ya que de acuerdo a la ley en el estado de Texas se debe proceder de manera diferente en cada caso.<\/p>\n<h3>\u00bfHay alguna diferencia a ra\u00edz del estatus migratorio de una persona?<\/h3>\n<p>No, no tiene absolutamente nada qu\u00e9 ver si la persona cuenta con un estatus legal o no al momento de reclamar por sus derechos.\u00a0<strong>En el estado de Texas al momento de reclamar por da\u00f1os y perjuicios no es necesario contar con un n\u00famero de Seguro Social.<\/strong><\/p>\n<p>Los casos que se reciben a menudo en el despacho de la Abogada Cristina son los relacionados con accidentes laborales en el \u00e1rea de la construcci\u00f3n. Son casos complejos porque existe un tipo de \u00ab\u00e1rea gris\u00bb en la que muchos de los empleados son Contratistas Independientes y nadie quiere hacerse cargo de los da\u00f1os causados en tales accidentes. Similar a lo que sucede en la industria de los restaurantes y la jardiner\u00eda, entre otras.<\/p>\n<p>En algunas ocasiones las compa\u00f1\u00edas que son contratadas para prestar \u00e9stos servicios, si son lo suficientemente grandes, cuentan con una p\u00f3liza llamada \u00abCompensaci\u00f3n Para Trabajadores\u00bb. Cuando esta p\u00f3liza existe es mucho m\u00e1s f\u00e1cil procesar reclamos por heridas ya que es el seguro del empleador el encargado de cubrir los gastos m\u00e9dicos y pagos que se deben hacer al empleado.<\/p>\n<p><strong>En Texas no es obligatorio para las empresas contar con esta p\u00f3liza por lo que es com\u00fan que las personas acudan a un abogado de accidentes de trabajo con estos casos.<\/strong>\u00a0Ella aconseja siempre tomar toda la informaci\u00f3n personal de la persona que lo contrate, ya que as\u00ed sea un trabajo de un solo d\u00eda, sin un nombre, apellido y direcci\u00f3n no ser\u00e1 posible llevar a cabo un proceso legal civil.<\/p>\n<h2>Derechos de los trabajadores<\/h2>\n<div id=\"attachment_15836\" class=\"wp-caption alignright\"><img decoding=\"async\" class=\"wp-image-15836 size-full\" src=\"https:\/\/www.lincolngoldfinch.com\/wp-content\/uploads\/2021\/10\/accidentes-de-construccion-reclamos-abogados-para-inmigrantes-texas.jpg\" alt=\"Accidentes Laborales Construccion Inmigrantes\" width=\"300\" height=\"199\" aria-describedby=\"caption-attachment-15836\" \/><\/div>\n<p>Todo trabajador tiene derecho a un lugar seguro de trabajo, dependiendo del tipo de trabajo que est\u00e9 llevando a cabo. Recientemente la firma de la abogada Cristina realiz\u00f3 una campa\u00f1a en redes sociales durante el verano respecto al \u00abGolpe de Calor\u00bb y las altas temperaturas que deben soportar los trabajadores en especial del \u00e1rea de la construcci\u00f3n, y la importancia para ellos de contar con descansos peri\u00f3dicos para hidratarse.<\/p>\n<p>Todas estas normas se encuentran reguladas por una entidad llamada\u00a0<a href=\"https:\/\/www.osha.gov\/\" target=\"_blank\" rel=\"noopener noreferrer\">OSHA (Administraci\u00f3n de Seguridad y Salud Ocupacional \u2013 Occupational Safety and Health Administration)<\/a>, que se encarga entre otras cosas de regular y multar a todas las empresas que no cumplan con los lineamientos de seguridad en el trabajo. En el sitio web de OSHA es posible encontrar dichos lineamientos exigidos por el Gobierno Federal dependiendo del tipo de trabajo que se haga, tambi\u00e9n las capacitaciones que dan completamente gratis.<\/p>\n<p>Cuando se hace un reclamo por las heridas causadas por un accidente, y este se debe a la negligencia de un tercero, se puede llevar a cabo\u00a0<strong>sin necesidad de que la v\u00edctima del accidente tenga un N\u00famero de Seguro Social<\/strong>. Al momento de analizar este tipo de casos es necesario determinar los porcentajes de culpabilidad de las partes, ya sea del trabajador o del empleador; bajo las leyes de Texas es necesario que el mayor porcentaje sea del empleador.<\/p>\n<p>Los beneficios a recuperar son los siguientes: gastos m\u00e9dicos pasados, presentes y futuros relacionados con el accidente, salarios perdidos pasados, presentes y futuros relacionados con el accidente, da\u00f1o y sufrimiento, discapacidad temporal o permanente, desfiguraci\u00f3n, da\u00f1o emocional, entre otros. Es importante procurar recibir atenci\u00f3n m\u00e9dica por el accidente lo m\u00e1s pronto posible, ya que la demora en la atenci\u00f3n puede ser utilizada como un argumento en contra de su caso.<\/p>\n<p>En el escenario de los testigos que deseen reclamar por su trauma, es necesario que el testigo sea familiar de la v\u00edctima y\/o que haya presenciado el accidente muy cercanamente, y que haya sido un suceso traum\u00e1tico. En caso de que la persona v\u00edctima haya fallecido, los reclamantes pueden ser los padres, c\u00f3nyuges o hijos, y en algunos casos los hermanos.<\/p>\n<p>En caso de tener preguntas adicionales respecto a alg\u00fan caso espec\u00edfico o los datos de contacto de la abogada de accidentes de trabajo Cristina, no dude en contactarnos al\u00a0<a href=\"tel:+1-855-502-0555\">(855) 502-0555<\/a>\u00a0para obtener una consulta con un abogado completamente gratis. Puede tambi\u00e9n seguirnos en nuestras redes sociales\u00a0<a href=\"https:\/\/www.facebook.com\/lincolngoldfinch\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>,\u00a0<a href=\"https:\/\/www.instagram.com\/lincolngoldfinchlaw\/?hl=en\" target=\"_blank\" rel=\"noopener noreferrer\">Instagram<\/a>,\u00a0<a href=\"https:\/\/www.youtube.com\/c\/Lincolngoldfinchlawatx\/\" target=\"_blank\" rel=\"noopener noreferrer\">YouTube<\/a>\u00a0y\u00a0<a href=\"https:\/\/www.tiktok.com\/@lincolngoldfinchlaw\/live\" target=\"_blank\" rel=\"noopener noreferrer\">TikTok<\/a>.<\/p>\n<\/div><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-two\" style=\"--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h2 class=\"fusion-title-heading title-heading-center\" style=\"margin:0;\">Preguntas Frecuentes Sobre Accidentes En El Trabajo<\/h2><\/div><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:1px;--awb-icon-size:16px;--awb-content-font-size:var(--awb-typography4-font-size);--awb-icon-alignment:left;--awb-hover-color:var(--awb-color2);--awb-border-color:var(--awb-color3);--awb-background-color:var(--awb-color1);--awb-divider-color:var(--awb-color3);--awb-divider-hover-color:var(--awb-color3);--awb-icon-color:var(--awb-color1);--awb-title-color:var(--awb-color8);--awb-content-color:var(--awb-color8);--awb-icon-box-color:var(--awb-color8);--awb-toggle-hover-accent-color:var(--awb-color5);--awb-title-font-family:var(--awb-typography1-font-family);--awb-title-font-weight:var(--awb-typography1-font-weight);--awb-title-font-style:var(--awb-typography1-font-style);--awb-title-font-size:var(--awb-typography1-font-size);--awb-content-font-family:var(--awb-typography4-font-family);--awb-content-font-weight:var(--awb-typography4-font-weight);--awb-content-font-style:var(--awb-typography4-font-style);\"><div class=\"panel-group fusion-toggle-icon-boxed\" id=\"accordion-15828-1\"><div class=\"fusion-panel panel-default panel-8230db0d3fecc57c2 fusion-toggle-has-divider\" style=\"--awb-title-font-size:20px;\"><div class=\"panel-heading\"><h3 class=\"panel-title toggle\" id=\"toggle_8230db0d3fecc57c2\"><a aria-expanded=\"false\" aria-controls=\"8230db0d3fecc57c2\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-15828-1\" data-target=\"#8230db0d3fecc57c2\" href=\"#8230db0d3fecc57c2\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfCu\u00e1l Es El Papel De Un Abogado De Accidentes De Trabajo?<\/span><\/a><\/h3><\/div><div id=\"8230db0d3fecc57c2\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_8230db0d3fecc57c2\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Es com\u00fan que en pa\u00edses como M\u00e9xico o pa\u00edses de habla hispana un abogado lleve varios tipos de casos. En Estados Unidos, y particularmente en Texas, esta situaci\u00f3n es diferente. Normalmente los abogados que toman casos de inmigraci\u00f3n, por ejemplo, se especializan en esos casos y no toman otro tipo de casos.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-9a6e45f359030ded4 fusion-toggle-has-divider\" style=\"--awb-title-font-size:20px;\"><div class=\"panel-heading\"><h3 class=\"panel-title toggle\" id=\"toggle_9a6e45f359030ded4\"><a aria-expanded=\"false\" aria-controls=\"9a6e45f359030ded4\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-15828-1\" data-target=\"#9a6e45f359030ded4\" href=\"#9a6e45f359030ded4\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfEs Posible Obtener Documentos Legales Como Resultado De Un Accidente De Auto?<\/span><\/a><\/h3><\/div><div id=\"9a6e45f359030ded4\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_9a6e45f359030ded4\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Depende del caso. Si usted fue v\u00edctima de un accidente automovil\u00edstico y la otra persona estaba intoxicada, entonces ese caso podr\u00eda calificar para una Visa U, y lo que hacen en la oficina de Cristina es ponerse en contacto con nuestra firma Lincoln-Goldfinch Law &#8211; Abogados de Inmigraci\u00f3n para un asesoramiento adecuado con respecto a qu\u00e9 camino tomar en materia de Inmigraci\u00f3n.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-46fdbcef19e4ec713 fusion-toggle-has-divider\" style=\"--awb-title-font-size:20px;\"><div class=\"panel-heading\"><h3 class=\"panel-title toggle\" id=\"toggle_46fdbcef19e4ec713\"><a aria-expanded=\"false\" aria-controls=\"46fdbcef19e4ec713\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-15828-1\" data-target=\"#46fdbcef19e4ec713\" href=\"#46fdbcef19e4ec713\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfExiste Alguna Diferencia Por El Estatus Legal De Inmigraci\u00f3n De Una Persona?<\/span><\/a><\/h3><\/div><div id=\"46fdbcef19e4ec713\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_46fdbcef19e4ec713\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>No, no tiene absolutamente nada que ver con que la persona tenga o no estatus legal en el momento de reclamar sus derechos.\u00a0En el estado de Texas, no se requiere un n\u00famero de la Seguridad Social para presentar una reclamaci\u00f3n por da\u00f1os y perjuicios.<\/p>\n<\/div><\/div><\/div><\/div><\/div><script type=\"application\/ld+json\">\n{\n\"@context\": \"https:\/\/schema.org\",\n\"@type\": \"FAQPage\",\n\"mainEntity\": [{\n\"@type\": \"Question\",\n\"name\": \"\u00bfCu\u00e1l Es El Papel De Un Abogado De Accidentes De Trabajo?\",\n\"acceptedAnswer\": {\n\"@type\": \"Answer\",\n\"text\": \"<p>Es com\u00fan que en pa\u00edses como M\u00e9xico o pa\u00edses de habla hispana un abogado lleve varios tipos de casos. En Estados Unidos, y particularmente en Texas, esta situaci\u00f3n es diferente. Normalmente los abogados que toman casos de inmigraci\u00f3n, por ejemplo, se especializan en esos casos y no toman otro tipo de casos.<\/p>\"\n}\n}, {\n\"@type\": \"Question\",\n\"name\": \"\u00bfEs Posible Obtener Documentos Legales Como Resultado De Un Accidente De Auto?\",\n\"acceptedAnswer\": {\n\"@type\": \"Answer\",\n\"text\": \"<p>Depende del caso. Si usted fue v\u00edctima de un accidente automovil\u00edstico y la otra persona estaba intoxicada, entonces ese caso podr\u00eda calificar para una Visa U, y lo que hacen en la oficina de Cristina es ponerse en contacto con nuestra firma Lincoln-Goldfinch Law para un asesoramiento adecuado con respecto a qu\u00e9 camino tomar en materia de Inmigraci\u00f3n.<\/p>\"\n}\n}, {\n\"@type\": \"Question\",\n\"name\": \"\u00bfExiste Alguna Diferencia Por El Estatus Legal De Inmigraci\u00f3n De Una Persona?\",\n\"acceptedAnswer\": {\n\"@type\": \"Answer\",\n\"text\": \"<p>No, no tiene absolutamente nada que ver con que la persona tenga o no estatus legal en el momento de reclamar sus derechos.\u00a0En el estado de Texas, no se requiere un n\u00famero de la Seguridad Social para presentar una reclamaci\u00f3n por da\u00f1os y perjuicios.<\/p>\"\n}\n}]\n}\n<\/script><\/div><\/div><\/div><\/div>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"vlog,inmigracion-vlogs-es\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1635229407\"\r\n\t            data-title=\"Accidentes en el trabajo\" \r\n\t            data-home=\"https:\/\/www.lincolngoldfinch.com\/es\/\"><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":15847,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","_analytify_skip_tracking":false,"rank_math_title":"Abogado de accidentes de trabajo - Conoce tus derechos","rank_math_description":"Cristina, nuestra invitada, explic\u00f3 en qu\u00e9 casos un inmigrante en Texas deber\u00eda contactar a un abogado de accidentes de trabajo.","rank_math_focus_keyword":"abogado de accidentes de trabajo","rank_math_canonical_url":"","footnotes":""},"categories":[1934,1938],"class_list":["post-15828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vlog","category-inmigracion-vlogs-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/posts\/15828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/comments?post=15828"}],"version-history":[{"count":0,"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/posts\/15828\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/media\/15847"}],"wp:attachment":[{"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/media?parent=15828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lincolngoldfinch.com\/es\/wp-json\/wp\/v2\/categories?post=15828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}